{"id":12194,"date":"2024-08-07T08:24:24","date_gmt":"2024-08-07T06:24:24","guid":{"rendered":"https:\/\/www.auxalia.com\/events\/autodesk-university-2024-in-san-diego\/"},"modified":"2025-07-30T15:19:39","modified_gmt":"2025-07-30T13:19:39","slug":"autodesk-university-2025-in-nashville","status":"publish","type":"events","link":"https:\/\/www.auxalia.com\/en\/events\/autodesk-university-2025-in-nashville\/","title":{"rendered":"Autodesk University 2025 in Nashville"},"content":{"rendered":"<p data-start=\"43\" data-end=\"319\">From September 16\u201318, 2025, the world\u2019s largest gathering of Autodesk customers\u2014Autodesk University\u2014will take place in Nashville, USA. At this flagship event for the Autodesk community, auxalia will also be showcasing its Plant Engineering division on the international stage.<\/p>\n<p data-start=\"321\" data-end=\"353\"><strong data-start=\"321\" data-end=\"353\">auxalia on site with a booth<\/strong><\/p>\n<p data-start=\"355\" data-end=\"659\">At our booth, customers and interested visitors can take an in\u2011depth look at our auxalia PlantTools. This series of specialized applications extends the Autodesk Plant Solutions products with valuable additional features that enable significant optimization of processes and workflows in 3D plant design.<\/p>\n<p data-start=\"661\" data-end=\"801\" data-is-last-node=\"\" data-is-only-node=\"\">Stop by and discuss your challenges and ideas for optimizing workflows for AutoCAD Plant 3D with our experts. We look forward to seeing you!<\/p>\n","protected":false},"featured_media":14294,"parent":0,"template":"","bereich":[113],"standort":[],"zeitraum":[],"event_categories":[],"class_list":["post-12194","events","type-events","status-publish","has-post-thumbnail","hentry","bereich-anlagenbau"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autodesk University 2025 in Nashville - auxalia GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auxalia.com\/en\/events\/autodesk-university-2025-in-nashville\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autodesk University 2025 in Nashville - auxalia GmbH\" \/>\n<meta property=\"og:description\" content=\"From September 16\u201318, 2025, the world\u2019s largest gathering of Autodesk customers\u2014Autodesk University\u2014will take place in Nashville, USA. At this flagship event for the Autodesk community, auxalia will also be showcasing its Plant Engineering division\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auxalia.com\/en\/events\/autodesk-university-2025-in-nashville\/\" \/>\n<meta property=\"og:site_name\" content=\"auxalia GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T13:19:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auxalia.com\/wp-content\/uploads\/2024\/08\/au2025_overview-web-banner_3200x1800px_1743707147939001tTga-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/events\\\/autodesk-university-2025-in-nashville\\\/\",\"url\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/events\\\/autodesk-university-2025-in-nashville\\\/\",\"name\":\"Autodesk University 2025 in Nashville - auxalia GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/events\\\/autodesk-university-2025-in-nashville\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/events\\\/autodesk-university-2025-in-nashville\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auxalia.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/au2025_overview-web-banner_3200x1800px_1743707147939001tTga-scaled.png\",\"datePublished\":\"2024-08-07T06:24:24+00:00\",\"dateModified\":\"2025-07-30T13:19:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/events\\\/autodesk-university-2025-in-nashville\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auxalia.com\\\/en\\\/events\\\/autodesk-university-2025-in-nashville\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/events\\\/autodesk-university-2025-in-nashville\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auxalia.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/au2025_overview-web-banner_3200x1800px_1743707147939001tTga-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.auxalia.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/au2025_overview-web-banner_3200x1800px_1743707147939001tTga-scaled.png\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/events\\\/autodesk-university-2025-in-nashville\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autodesk University 2025 in Nashville\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/\",\"name\":\"auxalia GmbH\",\"description\":\"Eine weitere WordPress-Website\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/#organization\",\"name\":\"auxalia GmbH\",\"url\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auxalia.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo_auxalia-with-group_blue-transparent.svg\",\"contentUrl\":\"https:\\\/\\\/www.auxalia.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo_auxalia-with-group_blue-transparent.svg\",\"caption\":\"auxalia GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auxalia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autodesk University 2025 in Nashville - auxalia GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auxalia.com\/en\/events\/autodesk-university-2025-in-nashville\/","og_locale":"en_US","og_type":"article","og_title":"Autodesk University 2025 in Nashville - auxalia GmbH","og_description":"From September 16\u201318, 2025, the world\u2019s largest gathering of Autodesk customers\u2014Autodesk University\u2014will take place in Nashville, USA. At this flagship event for the Autodesk community, auxalia will also be showcasing its Plant Engineering division","og_url":"https:\/\/www.auxalia.com\/en\/events\/autodesk-university-2025-in-nashville\/","og_site_name":"auxalia GmbH","article_modified_time":"2025-07-30T13:19:39+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.auxalia.com\/wp-content\/uploads\/2024\/08\/au2025_overview-web-banner_3200x1800px_1743707147939001tTga-scaled.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auxalia.com\/en\/events\/autodesk-university-2025-in-nashville\/","url":"https:\/\/www.auxalia.com\/en\/events\/autodesk-university-2025-in-nashville\/","name":"Autodesk University 2025 in Nashville - auxalia GmbH","isPartOf":{"@id":"https:\/\/www.auxalia.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auxalia.com\/en\/events\/autodesk-university-2025-in-nashville\/#primaryimage"},"image":{"@id":"https:\/\/www.auxalia.com\/en\/events\/autodesk-university-2025-in-nashville\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auxalia.com\/wp-content\/uploads\/2024\/08\/au2025_overview-web-banner_3200x1800px_1743707147939001tTga-scaled.png","datePublished":"2024-08-07T06:24:24+00:00","dateModified":"2025-07-30T13:19:39+00:00","breadcrumb":{"@id":"https:\/\/www.auxalia.com\/en\/events\/autodesk-university-2025-in-nashville\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auxalia.com\/en\/events\/autodesk-university-2025-in-nashville\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.auxalia.com\/en\/events\/autodesk-university-2025-in-nashville\/#primaryimage","url":"https:\/\/www.auxalia.com\/wp-content\/uploads\/2024\/08\/au2025_overview-web-banner_3200x1800px_1743707147939001tTga-scaled.png","contentUrl":"https:\/\/www.auxalia.com\/wp-content\/uploads\/2024\/08\/au2025_overview-web-banner_3200x1800px_1743707147939001tTga-scaled.png","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.auxalia.com\/en\/events\/autodesk-university-2025-in-nashville\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auxalia.com\/en\/"},{"@type":"ListItem","position":2,"name":"Autodesk University 2025 in Nashville"}]},{"@type":"WebSite","@id":"https:\/\/www.auxalia.com\/en\/#website","url":"https:\/\/www.auxalia.com\/en\/","name":"auxalia GmbH","description":"Eine weitere WordPress-Website","publisher":{"@id":"https:\/\/www.auxalia.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auxalia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.auxalia.com\/en\/#organization","name":"auxalia GmbH","url":"https:\/\/www.auxalia.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.auxalia.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.auxalia.com\/wp-content\/uploads\/2025\/02\/logo_auxalia-with-group_blue-transparent.svg","contentUrl":"https:\/\/www.auxalia.com\/wp-content\/uploads\/2025\/02\/logo_auxalia-with-group_blue-transparent.svg","caption":"auxalia GmbH"},"image":{"@id":"https:\/\/www.auxalia.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.auxalia.com\/en\/wp-json\/wp\/v2\/events\/12194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auxalia.com\/en\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/www.auxalia.com\/en\/wp-json\/wp\/v2\/types\/events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auxalia.com\/en\/wp-json\/wp\/v2\/media\/14294"}],"wp:attachment":[{"href":"https:\/\/www.auxalia.com\/en\/wp-json\/wp\/v2\/media?parent=12194"}],"wp:term":[{"taxonomy":"bereich","embeddable":true,"href":"https:\/\/www.auxalia.com\/en\/wp-json\/wp\/v2\/bereich?post=12194"},{"taxonomy":"standort","embeddable":true,"href":"https:\/\/www.auxalia.com\/en\/wp-json\/wp\/v2\/standort?post=12194"},{"taxonomy":"zeitraum","embeddable":true,"href":"https:\/\/www.auxalia.com\/en\/wp-json\/wp\/v2\/zeitraum?post=12194"},{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auxalia.com\/en\/wp-json\/wp\/v2\/event_categories?post=12194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}